{"id":265,"count":2,"description":"","link":"https:\/\/ftp.jmaceurope.com\/en\/category\/rd\/","name":"R&amp;D","slug":"rd","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R&amp;D Archivi - JMAC EUROPE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jmaceurope.com\/en\/category\/rd\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R&amp;D Archivi - JMAC EUROPE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jmaceurope.com\/en\/category\/rd\/\" \/>\n<meta property=\"og:site_name\" content=\"JMAC EUROPE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/jmaceurope.com\\\/en\\\/category\\\/rd\\\/\",\"url\":\"https:\\\/\\\/jmaceurope.com\\\/en\\\/category\\\/rd\\\/\",\"name\":\"R&amp;D Archivi - JMAC EUROPE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jmaceurope.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jmaceurope.com\\\/en\\\/category\\\/rd\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jmaceurope.com\\\/en\\\/category\\\/rd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jmaceurope.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R&amp;D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jmaceurope.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/jmaceurope.com\\\/en\\\/\",\"name\":\"JMAC EUROPE\",\"description\":\"JAPAN MANAGEMENT ASSOCIATION CONSULTANTS\",\"publisher\":{\"@id\":\"https:\\\/\\\/jmaceurope.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jmaceurope.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jmaceurope.com\\\/en\\\/#organization\",\"name\":\"JMAC Europe\",\"url\":\"https:\\\/\\\/jmaceurope.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jmaceurope.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"JMAC Europe\"},\"image\":{\"@id\":\"https:\\\/\\\/jmaceurope.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/jmac-europe-s-p-a-\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R&amp;D Archivi - JMAC EUROPE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jmaceurope.com\/en\/category\/rd\/","og_locale":"en_US","og_type":"article","og_title":"R&amp;D Archivi - JMAC EUROPE","og_url":"https:\/\/jmaceurope.com\/en\/category\/rd\/","og_site_name":"JMAC EUROPE","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jmaceurope.com\/en\/category\/rd\/","url":"https:\/\/jmaceurope.com\/en\/category\/rd\/","name":"R&amp;D Archivi - JMAC EUROPE","isPartOf":{"@id":"https:\/\/jmaceurope.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/jmaceurope.com\/en\/category\/rd\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/jmaceurope.com\/en\/category\/rd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jmaceurope.com\/en\/"},{"@type":"ListItem","position":2,"name":"R&amp;D"}]},{"@type":"WebSite","@id":"https:\/\/jmaceurope.com\/en\/#website","url":"https:\/\/jmaceurope.com\/en\/","name":"JMAC EUROPE","description":"JAPAN MANAGEMENT ASSOCIATION CONSULTANTS","publisher":{"@id":"https:\/\/jmaceurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jmaceurope.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/jmaceurope.com\/en\/#organization","name":"JMAC Europe","url":"https:\/\/jmaceurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jmaceurope.com\/en\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"JMAC Europe"},"image":{"@id":"https:\/\/jmaceurope.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/jmac-europe-s-p-a-\/"]}]}},"_links":{"self":[{"href":"https:\/\/ftp.jmaceurope.com\/en\/wp-json\/wp\/v2\/categories\/265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ftp.jmaceurope.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ftp.jmaceurope.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/ftp.jmaceurope.com\/en\/wp-json\/wp\/v2\/posts?categories=265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}